{"id":14547,"date":"2023-02-24T18:55:41","date_gmt":"2023-02-24T09:55:41","guid":{"rendered":"https:\/\/yuki-portal.com\/uploader\/koikatusunshine\/%e4%b8%8d%e5%b9%b8\/"},"modified":"2023-02-24T18:55:42","modified_gmt":"2023-02-24T09:55:42","slug":"%e4%b8%8d%e5%b9%b8","status":"publish","type":"post","link":"https:\/\/yuki-portal.com\/uploader\/koikatusunshine\/%e4%b8%8d%e5%b9%b8\/","title":{"rendered":"\u4e0d\u5e78"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":14548,"comment_status":"open","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[3,19],"acf":[],"_links":{"self":[{"href":"https:\/\/yuki-portal.com\/uploader\/koikatusunshine\/wp-json\/wp\/v2\/posts\/14547"}],"collection":[{"href":"https:\/\/yuki-portal.com\/uploader\/koikatusunshine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yuki-portal.com\/uploader\/koikatusunshine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yuki-portal.com\/uploader\/koikatusunshine\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/yuki-portal.com\/uploader\/koikatusunshine\/wp-json\/wp\/v2\/comments?post=14547"}],"version-history":[{"count":2,"href":"https:\/\/yuki-portal.com\/uploader\/koikatusunshine\/wp-json\/wp\/v2\/posts\/14547\/revisions"}],"predecessor-version":[{"id":14551,"href":"https:\/\/yuki-portal.com\/uploader\/koikatusunshine\/wp-json\/wp\/v2\/posts\/14547\/revisions\/14551"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/yuki-portal.com\/uploader\/koikatusunshine\/wp-json\/wp\/v2\/media\/14548"}],"wp:attachment":[{"href":"https:\/\/yuki-portal.com\/uploader\/koikatusunshine\/wp-json\/wp\/v2\/media?parent=14547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yuki-portal.com\/uploader\/koikatusunshine\/wp-json\/wp\/v2\/categories?post=14547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yuki-portal.com\/uploader\/koikatusunshine\/wp-json\/wp\/v2\/tags?post=14547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}