{"id":14525,"date":"2023-02-23T19:08:46","date_gmt":"2023-02-23T10:08:46","guid":{"rendered":"https:\/\/yuki-portal.com\/uploader\/koikatusunshine\/%e4%b8%8d%e8%89%af\/"},"modified":"2023-02-23T19:08:47","modified_gmt":"2023-02-23T10:08:47","slug":"%e4%b8%8d%e8%89%af","status":"publish","type":"post","link":"https:\/\/yuki-portal.com\/uploader\/koikatusunshine\/%e4%b8%8d%e8%89%af\/","title":{"rendered":"\u4e0d\u826f"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":14526,"comment_status":"open","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[3,19],"acf":[],"_links":{"self":[{"href":"https:\/\/yuki-portal.com\/uploader\/koikatusunshine\/wp-json\/wp\/v2\/posts\/14525"}],"collection":[{"href":"https:\/\/yuki-portal.com\/uploader\/koikatusunshine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yuki-portal.com\/uploader\/koikatusunshine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yuki-portal.com\/uploader\/koikatusunshine\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/yuki-portal.com\/uploader\/koikatusunshine\/wp-json\/wp\/v2\/comments?post=14525"}],"version-history":[{"count":2,"href":"https:\/\/yuki-portal.com\/uploader\/koikatusunshine\/wp-json\/wp\/v2\/posts\/14525\/revisions"}],"predecessor-version":[{"id":14529,"href":"https:\/\/yuki-portal.com\/uploader\/koikatusunshine\/wp-json\/wp\/v2\/posts\/14525\/revisions\/14529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/yuki-portal.com\/uploader\/koikatusunshine\/wp-json\/wp\/v2\/media\/14526"}],"wp:attachment":[{"href":"https:\/\/yuki-portal.com\/uploader\/koikatusunshine\/wp-json\/wp\/v2\/media?parent=14525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yuki-portal.com\/uploader\/koikatusunshine\/wp-json\/wp\/v2\/categories?post=14525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yuki-portal.com\/uploader\/koikatusunshine\/wp-json\/wp\/v2\/tags?post=14525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}