{"id":119032,"date":"2022-04-21T01:09:26","date_gmt":"2022-04-20T16:09:26","guid":{"rendered":"https:\/\/yuki-portal.com\/uploader\/honeyselect2\/other\/119032\/"},"modified":"2022-04-21T01:09:26","modified_gmt":"2022-04-20T16:09:26","slug":"ayako","status":"publish","type":"post","link":"https:\/\/yuki-portal.com\/uploader\/honeyselect2\/charadatacate\/chara_nonemod\/chara_nonemod_female\/119032\/","title":{"rendered":"Ayako"},"content":{"rendered":"\t\t\t\t\t\t\t<h2 id=\"dlfile\">\u30a2\u30c3\u30d7\u30ed\u30fc\u30c9\u30d5\u30a1\u30a4\u30eb\uff08\u30af\u30ea\u30c3\u30af\u3067\u30c0\u30a6\u30f3\u30ed\u30fc\u30c9\uff09<\/h2>\n\t\t\t\t\t<div class=\"postdl\">\n\t\t\t\t\t\t<a class=\"countable_link nossg\" href=\"https:\/\/yuki-portal.com\/uploader\/honeyselect2\/wp-content\/uploads\/2022\/04\/Ayako.png\"\n\t\t\t\t\t\t\tdownload=\"Ayako.png\"\n\t\t\t\t\t\t\tdata-id=\"119032\" data-name=\"dlcount\">\u30c0\u30a6\u30f3\u30ed\u30fc\u30c9\uff08147 KB\uff09<i class=\"fa fa-download\" aria-hidden=\"true\"><\/i>:317\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t","protected":false},"excerpt":{"rendered":"<p>\u30a2\u30c3\u30d7\u30ed\u30fc\u30c9\u30d5\u30a1\u30a4\u30eb\uff08\u30af\u30ea\u30c3\u30af\u3067\u30c0\u30a6\u30f3\u30ed\u30fc\u30c9\uff09 \u30c0\u30a6\u30f3\u30ed\u30fc\u30c9\uff08147 KB\uff09:317<\/p>\n","protected":false},"author":1575,"featured_media":119031,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[19],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/yuki-portal.com\/uploader\/honeyselect2\/wp-json\/wp\/v2\/posts\/119032"}],"collection":[{"href":"https:\/\/yuki-portal.com\/uploader\/honeyselect2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yuki-portal.com\/uploader\/honeyselect2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yuki-portal.com\/uploader\/honeyselect2\/wp-json\/wp\/v2\/users\/1575"}],"replies":[{"embeddable":true,"href":"https:\/\/yuki-portal.com\/uploader\/honeyselect2\/wp-json\/wp\/v2\/comments?post=119032"}],"version-history":[{"count":0,"href":"https:\/\/yuki-portal.com\/uploader\/honeyselect2\/wp-json\/wp\/v2\/posts\/119032\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/yuki-portal.com\/uploader\/honeyselect2\/wp-json\/wp\/v2\/media\/119031"}],"wp:attachment":[{"href":"https:\/\/yuki-portal.com\/uploader\/honeyselect2\/wp-json\/wp\/v2\/media?parent=119032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yuki-portal.com\/uploader\/honeyselect2\/wp-json\/wp\/v2\/categories?post=119032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yuki-portal.com\/uploader\/honeyselect2\/wp-json\/wp\/v2\/tags?post=119032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}